{"id":4271,"date":"2016-06-14T15:16:51","date_gmt":"2016-06-14T15:16:51","guid":{"rendered":"https:\/\/new.minisites.casadelmar.nl\/?p=4271"},"modified":"2023-11-29T12:40:34","modified_gmt":"2023-11-29T12:40:34","slug":"sendero-las-presas","status":"publish","type":"post","link":"https:\/\/salvia-sanpedro.com\/de\/sendero-las-presas\/","title":{"rendered":"Playa de Cortijo Blanco"},"content":{"rendered":"<p>Playa de Cortijo Blanco ist einer der Str\u00e4nde an der Costa del Sol, am westlichen Stadtrand von Marbella. Die Atmosph\u00e4re hier ist idyllisch und charmant: Zahlreiche Palmen spenden Schatten und werten das Erscheinungsbild entlang des gepflegten Boulevards auf. Umfangreiche Chiringuitos bieten hochwertige Getr\u00e4nke und Speisen, viele Sitzgelegenheiten im Freien und einige Sonnenliegen am privaten Pool.<\/p>","protected":false},"excerpt":{"rendered":"<p>Playa de Cortijo Blanco ist einer der Str\u00e4nde an der Costa del Sol, am westlichen Stadtrand von Marbella. Die Atmosph\u00e4re hier ist idyllisch und charmant: Zahlreiche Palmen spenden Schatten und werten das Erscheinungsbild entlang des gepflegten Boulevards auf. Umfangreiche Chiringuitos bieten Getr\u00e4nke und Essen auf hohem Niveau, viele Sitzgelegenheiten im Freien und einige Sonnenliegen \u2026 <a class=\"more-link\" href=\"https:\/\/salvia-sanpedro.com\/de\/sendero-las-presas\/\">Weiterlesen<\/a><\/p>","protected":false},"author":1,"featured_media":4317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Playa de Cortijo Blanco - Salvia - San Pedro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salvia-sanpedro.com\/de\/sendero-las-presas\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playa de Cortijo Blanco - Salvia - San Pedro\" \/>\n<meta property=\"og:description\" content=\"Playa de Cortijo Blanco is \u00e9\u00e9n van de stranden aan de Costa del Sol, langs de westelijke buitenwijken van Marbella. De sfeer is hier idyllisch en charmant: talrijke palmbomen zorgen voor schaduw en verfraaien de verschijning langs de verzorgde boulevard. Uitgebreide chiringuitos bieden drankjes en eten op hoog niveau, veel buitenzitjes en enkele ligbedden bij [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salvia-sanpedro.com\/de\/sendero-las-presas\/\" \/>\n<meta property=\"og:site_name\" content=\"Salvia - San Pedro\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-14T15:16:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-29T12:40:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salvia-sanpedro.com\/wp-content\/uploads\/sites\/33\/2016\/06\/playacortijo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/#\\\/schema\\\/person\\\/a6d0c79178eefd61bc222277458bf3ed\"},\"headline\":\"Playa de Cortijo Blanco\",\"datePublished\":\"2016-06-14T15:16:51+00:00\",\"dateModified\":\"2023-11-29T12:40:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/\"},\"wordCount\":62,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salvia-sanpedro.com\\\/wp-content\\\/uploads\\\/sites\\\/33\\\/2016\\\/06\\\/playacortijo.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/\",\"url\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/\",\"name\":\"Playa de Cortijo Blanco - Salvia - San Pedro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salvia-sanpedro.com\\\/wp-content\\\/uploads\\\/sites\\\/33\\\/2016\\\/06\\\/playacortijo.jpg\",\"datePublished\":\"2016-06-14T15:16:51+00:00\",\"dateModified\":\"2023-11-29T12:40:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/#\\\/schema\\\/person\\\/a6d0c79178eefd61bc222277458bf3ed\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salvia-sanpedro.com\\\/wp-content\\\/uploads\\\/sites\\\/33\\\/2016\\\/06\\\/playacortijo.jpg\",\"contentUrl\":\"https:\\\/\\\/salvia-sanpedro.com\\\/wp-content\\\/uploads\\\/sites\\\/33\\\/2016\\\/06\\\/playacortijo.jpg\",\"width\":480,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/sendero-las-presas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salvia-sanpedro.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Playa de Cortijo Blanco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/#website\",\"url\":\"https:\\\/\\\/salvia-sanpedro.com\\\/\",\"name\":\"Salvia - San Pedro\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salvia-sanpedro.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/salvia-sanpedro.com\\\/#\\\/schema\\\/person\\\/a6d0c79178eefd61bc222277458bf3ed\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/minisites.casadelmar.nl\"],\"url\":\"https:\\\/\\\/salvia-sanpedro.com\\\/de\\\/author\\\/admin_h89wrrhq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Playa de Cortijo Blanco \u2013 Salvia \u2013 San Pedro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salvia-sanpedro.com\/de\/sendero-las-presas\/","og_locale":"de_DE","og_type":"article","og_title":"Playa de Cortijo Blanco - Salvia - San Pedro","og_description":"Playa de Cortijo Blanco is \u00e9\u00e9n van de stranden aan de Costa del Sol, langs de westelijke buitenwijken van Marbella. De sfeer is hier idyllisch en charmant: talrijke palmbomen zorgen voor schaduw en verfraaien de verschijning langs de verzorgde boulevard. Uitgebreide chiringuitos bieden drankjes en eten op hoog niveau, veel buitenzitjes en enkele ligbedden bij [&hellip;]","og_url":"https:\/\/salvia-sanpedro.com\/de\/sendero-las-presas\/","og_site_name":"Salvia - San Pedro","article_published_time":"2016-06-14T15:16:51+00:00","article_modified_time":"2023-11-29T12:40:34+00:00","og_image":[{"width":480,"height":320,"url":"https:\/\/salvia-sanpedro.com\/wp-content\/uploads\/sites\/33\/2016\/06\/playacortijo.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/#article","isPartOf":{"@id":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/"},"author":{"name":"admin","@id":"https:\/\/salvia-sanpedro.com\/#\/schema\/person\/a6d0c79178eefd61bc222277458bf3ed"},"headline":"Playa de Cortijo Blanco","datePublished":"2016-06-14T15:16:51+00:00","dateModified":"2023-11-29T12:40:34+00:00","mainEntityOfPage":{"@id":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/"},"wordCount":62,"commentCount":0,"image":{"@id":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/#primaryimage"},"thumbnailUrl":"https:\/\/salvia-sanpedro.com\/wp-content\/uploads\/sites\/33\/2016\/06\/playacortijo.jpg","articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/salvia-sanpedro.com\/sendero-las-presas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/","url":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/","name":"Playa de Cortijo Blanco \u2013 Salvia \u2013 San Pedro","isPartOf":{"@id":"https:\/\/salvia-sanpedro.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/#primaryimage"},"image":{"@id":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/#primaryimage"},"thumbnailUrl":"https:\/\/salvia-sanpedro.com\/wp-content\/uploads\/sites\/33\/2016\/06\/playacortijo.jpg","datePublished":"2016-06-14T15:16:51+00:00","dateModified":"2023-11-29T12:40:34+00:00","author":{"@id":"https:\/\/salvia-sanpedro.com\/#\/schema\/person\/a6d0c79178eefd61bc222277458bf3ed"},"breadcrumb":{"@id":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salvia-sanpedro.com\/sendero-las-presas\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/#primaryimage","url":"https:\/\/salvia-sanpedro.com\/wp-content\/uploads\/sites\/33\/2016\/06\/playacortijo.jpg","contentUrl":"https:\/\/salvia-sanpedro.com\/wp-content\/uploads\/sites\/33\/2016\/06\/playacortijo.jpg","width":480,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/salvia-sanpedro.com\/sendero-las-presas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salvia-sanpedro.com\/"},{"@type":"ListItem","position":2,"name":"Playa de Cortijo Blanco"}]},{"@type":"WebSite","@id":"https:\/\/salvia-sanpedro.com\/#website","url":"https:\/\/salvia-sanpedro.com\/","name":"Salvia - San Pedro","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salvia-sanpedro.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/salvia-sanpedro.com\/#\/schema\/person\/a6d0c79178eefd61bc222277458bf3ed","name":"Administrator","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eae4be199865be7f05f9ea08f18551c721d94e8b2649e22a432497875a2f6905?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/minisites.casadelmar.nl"],"url":"https:\/\/salvia-sanpedro.com\/de\/author\/admin_h89wrrhq\/"}]}},"_links":{"self":[{"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/posts\/4271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/comments?post=4271"}],"version-history":[{"count":3,"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/posts\/4271\/revisions"}],"predecessor-version":[{"id":4318,"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/posts\/4271\/revisions\/4318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/media\/4317"}],"wp:attachment":[{"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/media?parent=4271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/categories?post=4271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salvia-sanpedro.com\/de\/wp-json\/wp\/v2\/tags?post=4271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}